{"id":14582,"date":"2024-09-09T07:23:42","date_gmt":"2024-09-09T07:23:42","guid":{"rendered":"https:\/\/timberwalls.net\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/"},"modified":"2024-10-28T13:06:32","modified_gmt":"2024-10-28T13:06:32","slug":"murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais","status":"publish","type":"post","link":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/","title":{"rendered":"Murs en bois : Construire des maisons durables pour le paysage islandais"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]\t\t\t<link rel=\"stylesheet\" id=\"wd-text-block-css\" href=\"https:\/\/timberwalls.net\/wp-content\/themes\/woodmart\/css\/parts\/el-text-block.min.css?ver=7.5.2\" type=\"text\/css\" media=\"all\" \/> \t\t\t\t\t<div id=\"wd-66d9a57e53a58\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-66d9a57e53a58 text-left \">\n\t\t\t<p data-sourcepos=\"3:1-3:313\"><strong>Timberwalls<\/strong>, pionnier de la construction durable en bois, est fier d&rsquo;annoncer son expansion sur le magnifique et unique march\u00e9 islandais. Avec une exp\u00e9rience reconnue dans la livraison de maisons \u00e0 ossature bois de haute qualit\u00e9, \u00e9nerg\u00e9tiquement efficaces et esth\u00e9tiquement agr\u00e9ables, Timberwalls est bien plac\u00e9 pour r\u00e9pondre aux besoins sp\u00e9cifiques et aux pr\u00e9f\u00e9rences des propri\u00e9taires islandais. <\/p>\n<div class=\"container\"><\/div>\n\t\t<\/div>\n\t\t[\/vc_column][\/vc_row][vc_row content_placement=\u00a0\u00bbtop\u00a0\u00bb][vc_column offset=\u00a0\u00bbvc_col-md-6&Prime;]\t\t<div id=\"wd-66d9a59fb8008\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-66d9a59fb8008 text-left \">\n\t\t\t<p data-sourcepos=\"5:1-5:34\"><strong>Embrasser l&rsquo;esprit islandais<\/strong><\/p>\n<p data-sourcepos=\"7:1-7:31\">L&rsquo;Islande, pays aux paysages \u00e9poustouflants et fortement engag\u00e9 dans le d\u00e9veloppement durable, pr\u00e9sente un ensemble unique de d\u00e9fis et d&rsquo;opportunit\u00e9s pour la construction. Timberwalls comprend l&rsquo;importance de cr\u00e9er des maisons qui non seulement r\u00e9sistent au rude climat islandais, mais qui s&rsquo;harmonisent \u00e9galement avec la beaut\u00e9 naturelle du pays. <\/p>\n\t\t<\/div>\n\t\t[\/vc_column][vc_column offset=\u00a0\u00bbvc_col-md-6&Prime; css=\u00a0\u00bb.vc_custom_1490106506092{margin-bottom: 20px !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb13883&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb wd_animation_duration=\u00a0\u00bbslow\u00a0\u00bb parallax_scroll=\u00a0\u00bbno\u00a0\u00bb woodmart_inline=\u00a0\u00bbno\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column]\t\t<div id=\"wd-66d9a5bc84b9b\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-66d9a5bc84b9b text-left \">\n\t\t\t<p data-sourcepos=\"9:1-9:37\"><strong>Adapt\u00e9 aux conditions islandaises<\/strong><\/p>\n<p data-sourcepos=\"11:1-11:139\">La technologie innovante des panneaux \u00e0 ossature bois de Timberwalls offre plusieurs avantages qui sont particuli\u00e8rement bien adapt\u00e9s au march\u00e9 islandais :<\/p>\n<ul data-sourcepos=\"13:1-15:161\">\n<li data-sourcepos=\"13:1-13:152\"><strong>Une isolation exceptionnelle :<\/strong> Nos b\u00e2timents int\u00e8grent des syst\u00e8mes d&rsquo;isolation avanc\u00e9s pour fournir une chaleur et un confort optimaux pendant les hivers froids de l&rsquo;Islande.<\/li>\n<li data-sourcepos=\"14:1-14:153\"><strong>R\u00e9sistance aux intemp\u00e9ries :<\/strong> Les structures de Timberwalls sont con\u00e7ues pour r\u00e9sister aux vents violents, aux fortes chutes de neige et aux cendres volcaniques qui peuvent survenir en Islande.<\/li>\n<li data-sourcepos=\"15:1-15:161\"><strong>Efficacit\u00e9 \u00e9nerg\u00e9tique :<\/strong> Nos conceptions \u00e0 haut rendement \u00e9nerg\u00e9tique aident les propri\u00e9taires \u00e0 r\u00e9duire leur consommation d&rsquo;\u00e9nergie et leurs factures d&rsquo;\u00e9lectricit\u00e9, ce qui les rend plus durables et plus rentables.<\/li>\n<li data-sourcepos=\"16:1-16:167\"><strong>Beaut\u00e9 naturelle :<\/strong> L&rsquo;approche esth\u00e9tique de Timberwalls compl\u00e8te la beaut\u00e9 naturelle de l&rsquo;Islande, en cr\u00e9ant des maisons qui s&rsquo;int\u00e8grent parfaitement \u00e0 l&rsquo;environnement.<\/li>\n<li data-sourcepos=\"17:1-18:0\"><strong>Personnalisation et flexibilit\u00e9 :<\/strong> Nous offrons un haut degr\u00e9 de personnalisation, permettant aux propri\u00e9taires islandais de cr\u00e9er des espaces de vie personnalis\u00e9s qui refl\u00e8tent leur style unique et leurs pr\u00e9f\u00e9rences.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t[\/vc_column][\/vc_row][vc_row content_placement=\u00a0\u00bbtop\u00a0\u00bb][vc_column css=\u00a0\u00bb.vc_custom_1490106739180{margin-bottom: 20px !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_col-md-6&Prime;][vc_single_image image=\u00a0\u00bb13889&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb parallax_scroll=\u00a0\u00bbno\u00a0\u00bb woodmart_inline=\u00a0\u00bbno\u00a0\u00bb][\/vc_column][vc_column offset=\u00a0\u00bbvc_col-md-6&Prime;]\t\t<div id=\"wd-66d9a5ed1a975\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-66d9a5ed1a975 text-left \">\n\t\t\t<p data-sourcepos=\"19:1-19:33\"><strong>Soutenir un mode de vie durable<\/strong><\/p>\n<p data-sourcepos=\"21:1-21:335\">Timberwalls s&rsquo;engage \u00e0 soutenir un mode de vie durable en Islande. Notre utilisation de mat\u00e9riaux en bois durable, associ\u00e9e \u00e0 nos conceptions \u00e9co\u00e9nerg\u00e9tiques, contribue \u00e0 r\u00e9duire l&#8217;empreinte carbone de nos b\u00e2timents. En outre, nous \u00e9tudions les possibilit\u00e9s de nous approvisionner en bois localement ou \u00e0 partir de pratiques foresti\u00e8res durables dans des climats similaires.  <\/p>\n\t\t<\/div>\n\t\t[\/vc_column][\/vc_row][vc_row][vc_column]\t\t<div id=\"wd-66d9a608ba971\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-66d9a608ba971 text-left \">\n\t\t\t<p data-sourcepos=\"23:1-23:14\"><strong>Conclusion<\/strong><\/p>\n<p data-sourcepos=\"25:1-25:6\">Timberwalls est enthousiaste \u00e0 l&rsquo;id\u00e9e de contribuer au dynamisme du march\u00e9 islandais du logement en proposant des maisons \u00e0 ossature bois durables et esth\u00e9tiques. Nous sommes convaincus que notre approche innovante r\u00e9pondra aux besoins uniques des propri\u00e9taires islandais et contribuera \u00e0 cr\u00e9er un avenir plus durable et plus prosp\u00e8re pour le pays. <\/p>\n\t\t<\/div>\n\t\t[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row content_placement=\u00a0\u00bbtop\u00a0\u00bb][vc_column offset=\u00a0\u00bbvc_col-md-6&Prime;][\/vc_column][vc_column offset=\u00a0\u00bbvc_col-md-6&Prime; css=\u00a0\u00bb.vc_custom_1490106506092{margin-bottom: 20px !important;}\u00a0\u00bb][vc_single_image image=\u00a0\u00bb13883&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb css=\u00a0\u00bb\u00a0\u00bb wd_animation_duration=\u00a0\u00bbslow\u00a0\u00bb parallax_scroll=\u00a0\u00bbno\u00a0\u00bb woodmart_inline=\u00a0\u00bbno\u00a0\u00bb][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row content_placement=\u00a0\u00bbtop\u00a0\u00bb][vc_column css=\u00a0\u00bb.vc_custom_1490106739180{margin-bottom: 20px !important;}\u00a0\u00bb offset=\u00a0\u00bbvc_col-md-6&Prime;][vc_single_image image=\u00a0\u00bb13889&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb<\/p>\n","protected":false},"author":3,"featured_media":14650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132],"tags":[],"class_list":["post-14582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Murs en bois : Construire des maisons durables pour le paysage islandais - timberwalls.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Murs en bois : Construire des maisons durables pour le paysage islandais - timberwalls.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/\" \/>\n<meta property=\"og:site_name\" content=\"timberwalls.net\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-09T07:23:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T13:06:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"administratorius\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"administratorius\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/\"},\"author\":{\"name\":\"administratorius\",\"@id\":\"https:\/\/timberwalls.net\/de\/#\/schema\/person\/cdba70f3cad36cb90f356bde20f9aad0\"},\"headline\":\"Murs en bois : Construire des maisons durables pour le paysage islandais\",\"datePublished\":\"2024-09-09T07:23:42+00:00\",\"dateModified\":\"2024-10-28T13:06:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/\"},\"wordCount\":895,\"publisher\":{\"@id\":\"https:\/\/timberwalls.net\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg\",\"articleSection\":[\"Inspiration\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/\",\"url\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/\",\"name\":\"Murs en bois : Construire des maisons durables pour le paysage islandais - timberwalls.net\",\"isPartOf\":{\"@id\":\"https:\/\/timberwalls.net\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg\",\"datePublished\":\"2024-09-09T07:23:42+00:00\",\"dateModified\":\"2024-10-28T13:06:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#primaryimage\",\"url\":\"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg\",\"contentUrl\":\"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/timberwalls.net\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Murs en bois : Construire des maisons durables pour le paysage islandais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/timberwalls.net\/de\/#website\",\"url\":\"https:\/\/timberwalls.net\/de\/\",\"name\":\"timberwalls.net\",\"description\":\"timberwalls.net\",\"publisher\":{\"@id\":\"https:\/\/timberwalls.net\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/timberwalls.net\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/timberwalls.net\/de\/#organization\",\"name\":\"Wooden frame-panel houses\",\"url\":\"https:\/\/timberwalls.net\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/timberwalls.net\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/08\/Timberwalls-logo-1.jpg\",\"contentUrl\":\"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/08\/Timberwalls-logo-1.jpg\",\"width\":960,\"height\":685,\"caption\":\"Wooden frame-panel houses\"},\"image\":{\"@id\":\"https:\/\/timberwalls.net\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/timberwalls.net\/de\/#\/schema\/person\/cdba70f3cad36cb90f356bde20f9aad0\",\"name\":\"administratorius\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/timberwalls.net\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/284fd1bad45f053b3b6a4093d7e4d87f226f2a85895438e8a29f0863bc3d2bb6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/284fd1bad45f053b3b6a4093d7e4d87f226f2a85895438e8a29f0863bc3d2bb6?s=96&d=mm&r=g\",\"caption\":\"administratorius\"},\"url\":\"https:\/\/timberwalls.net\/fr\/author\/administratorius\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Murs en bois : Construire des maisons durables pour le paysage islandais - timberwalls.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/","og_locale":"fr_FR","og_type":"article","og_title":"Murs en bois : Construire des maisons durables pour le paysage islandais - timberwalls.net","og_url":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/","og_site_name":"timberwalls.net","article_published_time":"2024-09-09T07:23:42+00:00","article_modified_time":"2024-10-28T13:06:32+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg","type":"image\/jpeg"}],"author":"administratorius","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"administratorius","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#article","isPartOf":{"@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/"},"author":{"name":"administratorius","@id":"https:\/\/timberwalls.net\/de\/#\/schema\/person\/cdba70f3cad36cb90f356bde20f9aad0"},"headline":"Murs en bois : Construire des maisons durables pour le paysage islandais","datePublished":"2024-09-09T07:23:42+00:00","dateModified":"2024-10-28T13:06:32+00:00","mainEntityOfPage":{"@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/"},"wordCount":895,"publisher":{"@id":"https:\/\/timberwalls.net\/de\/#organization"},"image":{"@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#primaryimage"},"thumbnailUrl":"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg","articleSection":["Inspiration"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/","url":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/","name":"Murs en bois : Construire des maisons durables pour le paysage islandais - timberwalls.net","isPartOf":{"@id":"https:\/\/timberwalls.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#primaryimage"},"image":{"@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#primaryimage"},"thumbnailUrl":"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg","datePublished":"2024-09-09T07:23:42+00:00","dateModified":"2024-10-28T13:06:32+00:00","breadcrumb":{"@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#primaryimage","url":"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg","contentUrl":"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/09\/5924d92d1d93f5376bddd21ecb00a0d205ba4253-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/timberwalls.net\/fr\/2024\/09\/09\/murs-en-bois-construire-des-maisons-durables-pour-le-paysage-islandais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/timberwalls.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Murs en bois : Construire des maisons durables pour le paysage islandais"}]},{"@type":"WebSite","@id":"https:\/\/timberwalls.net\/de\/#website","url":"https:\/\/timberwalls.net\/de\/","name":"timberwalls.net","description":"timberwalls.net","publisher":{"@id":"https:\/\/timberwalls.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/timberwalls.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/timberwalls.net\/de\/#organization","name":"Wooden frame-panel houses","url":"https:\/\/timberwalls.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/timberwalls.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/08\/Timberwalls-logo-1.jpg","contentUrl":"https:\/\/timberwalls.net\/wp-content\/uploads\/2024\/08\/Timberwalls-logo-1.jpg","width":960,"height":685,"caption":"Wooden frame-panel houses"},"image":{"@id":"https:\/\/timberwalls.net\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/timberwalls.net\/de\/#\/schema\/person\/cdba70f3cad36cb90f356bde20f9aad0","name":"administratorius","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/timberwalls.net\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/284fd1bad45f053b3b6a4093d7e4d87f226f2a85895438e8a29f0863bc3d2bb6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/284fd1bad45f053b3b6a4093d7e4d87f226f2a85895438e8a29f0863bc3d2bb6?s=96&d=mm&r=g","caption":"administratorius"},"url":"https:\/\/timberwalls.net\/fr\/author\/administratorius\/"}]}},"_links":{"self":[{"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/posts\/14582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/comments?post=14582"}],"version-history":[{"count":10,"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/posts\/14582\/revisions"}],"predecessor-version":[{"id":14742,"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/posts\/14582\/revisions\/14742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/media\/14650"}],"wp:attachment":[{"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/media?parent=14582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/categories?post=14582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timberwalls.net\/fr\/wp-json\/wp\/v2\/tags?post=14582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}